{"id":18333,"date":"2022-11-02T10:00:00","date_gmt":"2021-12-29T07:11:16","guid":{"rendered":"https:\/\/annettemorris.art\/?post_type=tribe_events&#038;eventDate=2024-08-07#038;eventDate=2022-11-02#038;p=16152"},"modified":"2023-05-01T14:18:43","modified_gmt":"2023-05-01T12:18:43","slug":"travel-sketching-tour-hosted-by-french-fusion-travel","status":"publish","type":"tribe_events","link":"https:\/\/annettemorris.art\/fr\/event\/travel-sketching-tour-hosted-by-french-fusion-travel\/","title":{"rendered":"South of France Travel Sketching Tour"},"content":{"rendered":"<p>A very special fully guided tour and 10 fabulous days of sketching and watercolour workshops exploring the magnificent Languedoc region of Southern France.<\/p>\n<p>You will be staying in a beautiful private mansion with gardens and pool not far from B\u00e9ziers and the Mediterranean coast.<\/p>\n<p>Live like a local and enjoy daily classes and lots of fun with myself and your tour host Kate Stedman at <a href=\"https:\/\/frenchfusion.com.au\/tours\/france-travel-sketching-with-annette-morris-june-2023\" target=\"_blank\" rel=\"noopener\"><strong>French Fusion Travel<\/strong><\/a>.<\/p>\n<p>If you&rsquo;d like to find out more about joining for the full trip or just a few days, please get in touch <a href=\"mailto:annette@sketchingfrance.com\" target=\"_blank\" rel=\"noopener\">annette@sketchingfrance.com<\/a><\/p>\n<div class=\"kad-mosaic-gallery-wrapper\"><div id=\"kad-wp-gallery767\" class=\"kad-wp-gallery gallery reinit-isotope init-mosaic-isotope kad-light-gallery row-nomargin clearfix\" data-iso-selector=\".g_item\" data-iso-style=\"packery\" data-mosaic-selector=\".mosaic-grid-size\" data-iso-filter=\"false\"><div class=\"col-xxl-25 col-xl-3 col-md-3 col-sm-4 col-xs-4 col-ss-4 mosaic-tall-grid-size g_item g_item_1\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item g_mosiac_item grid_mosiac_item\" style=\"padding-bottom:200%;\"><div class=\"g_mosiac_item_inner\"><a href=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/MQ-Wedding48-scaled.jpeg\" data-rel=\"lightbox\" class=\"gallery-link\"><div class=\"g_mosiac_item_image_case kt-intrinsic\"><div itemprop=\"image\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"800\" src=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/MQ-Wedding48-scaled-400x800.jpeg\" srcset=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/MQ-Wedding48-scaled-400x800.jpeg 400w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/MQ-Wedding48-scaled-800x1600.jpeg 800w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\"  class=\"kt-gallery-img\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/MQ-Wedding48-scaled-400x800.jpeg\"><meta itemprop=\"width\" content=\"400px\"><meta itemprop=\"height\" content=\"800px\"><\/div><\/div><\/a><\/div><\/div><\/div><div class=\"col-xxl-40 col-xl-6 col-md-6 col-sm-8 col-xs-8 col-ss-8 g_item g_item_2\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item g_mosiac_item grid_mosiac_item\" style=\"padding-bottom:50%;\"><div class=\"g_mosiac_item_inner\"><a href=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/kate-sketching-bize-scaled.jpeg\" data-rel=\"lightbox\" class=\"gallery-link\"><div class=\"g_mosiac_item_image_case kt-intrinsic\"><div itemprop=\"image\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/kate-sketching-bize-scaled-800x400.jpeg\" srcset=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/kate-sketching-bize-scaled-800x400.jpeg 800w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/kate-sketching-bize-scaled-1600x800.jpeg 1600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\"  class=\"kt-gallery-img\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/kate-sketching-bize-scaled-800x400.jpeg\"><meta itemprop=\"width\" content=\"800px\"><meta itemprop=\"height\" content=\"400px\"><\/div><\/div><\/a><\/div><\/div><\/div><div class=\"col-xxl-25 col-xl-3 col-md-3 col-sm-4 col-xs-4 col-ss-4 mosaic-grid-size g_item g_item_3\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item g_mosiac_item grid_mosiac_item\" style=\"padding-bottom:100%;\"><div class=\"g_mosiac_item_inner\"><a href=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/hb-hh-hall-460-k_orig.jpeg\" data-rel=\"lightbox\" class=\"gallery-link\"><div class=\"g_mosiac_item_image_case kt-intrinsic\"><div itemprop=\"image\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/hb-hh-hall-460-k_orig-400x400.jpeg\" srcset=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/hb-hh-hall-460-k_orig-400x400.jpeg 400w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/hb-hh-hall-460-k_orig-150x150.jpeg 150w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/hb-hh-hall-460-k_orig-100x100.jpeg 100w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\"  class=\"kt-gallery-img\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/hb-hh-hall-460-k_orig-400x400.jpeg\"><meta itemprop=\"width\" content=\"400px\"><meta itemprop=\"height\" content=\"400px\"><\/div><\/div><\/a><\/div><\/div><\/div><div class=\"col-xxl-25 col-xl-3 col-md-3 col-sm-4 col-xs-4 col-ss-4 mosaic-grid-size g_item g_item_4\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item g_mosiac_item grid_mosiac_item\" style=\"padding-bottom:100%;\"><div class=\"g_mosiac_item_inner\"><a href=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/place-aux-huiles.jpeg\" data-rel=\"lightbox\" class=\"gallery-link\"><div class=\"g_mosiac_item_image_case kt-intrinsic\"><div itemprop=\"image\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/place-aux-huiles-400x400.jpeg\" srcset=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/place-aux-huiles-400x400.jpeg 400w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/place-aux-huiles-300x300.jpeg 300w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/place-aux-huiles-1024x1024.jpeg 1024w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/place-aux-huiles-150x150.jpeg 150w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/place-aux-huiles-768x768.jpeg 768w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/place-aux-huiles-1536x1536.jpeg 1536w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/place-aux-huiles-2048x2048.jpeg 2048w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/place-aux-huiles-500x500.jpeg 500w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/place-aux-huiles-100x100.jpeg 100w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/place-aux-huiles-800x800.jpeg 800w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/place-aux-huiles.jpeg 2075w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\"  class=\"kt-gallery-img\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/place-aux-huiles-400x400.jpeg\"><meta itemprop=\"width\" content=\"400px\"><meta itemprop=\"height\" content=\"400px\"><\/div><\/div><\/a><\/div><\/div><\/div><div class=\"col-xxl-40 col-xl-6 col-md-6 col-sm-4 col-xs-4 col-ss-12 g_item g_item_5\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item g_mosiac_item grid_mosiac_item\" style=\"padding-bottom:100%;\"><div class=\"g_mosiac_item_inner\"><a href=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/quarante-1-scaled.jpeg\" data-rel=\"lightbox\" class=\"gallery-link\"><div class=\"g_mosiac_item_image_case kt-intrinsic\"><div itemprop=\"image\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/quarante-1-scaled-800x800.jpeg\" srcset=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/quarante-1-scaled-800x800.jpeg 800w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/quarante-1-150x150.jpeg 150w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/quarante-1-100x100.jpeg 100w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/quarante-1-scaled-1600x1600.jpeg 1600w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/quarante-1-scaled-400x400.jpeg 400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\"  class=\"kt-gallery-img\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/quarante-1-scaled-800x800.jpeg\"><meta itemprop=\"width\" content=\"800px\"><meta itemprop=\"height\" content=\"800px\"><\/div><\/div><\/a><\/div><\/div><\/div><div class=\"col-xxl-40 col-xl-6 col-md-6 col-sm-8 col-xs-8 col-ss-12 g_item g_item_6\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item g_mosiac_item grid_mosiac_item\" style=\"padding-bottom:50%;\"><div class=\"g_mosiac_item_inner\"><a href=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/img-0470_orig.jpeg\" data-rel=\"lightbox\" class=\"gallery-link\"><div class=\"g_mosiac_item_image_case kt-intrinsic\"><div itemprop=\"image\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/img-0470_orig-800x400.jpeg\"    class=\"kt-gallery-img\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/img-0470_orig-800x400.jpeg\"><meta itemprop=\"width\" content=\"800px\"><meta itemprop=\"height\" content=\"400px\"><\/div><\/div><\/a><\/div><\/div><\/div><div class=\"col-xxl-25 col-xl-3 col-md-3 col-sm-4 col-xs-4 col-ss-4 mosaic-tall-grid-size g_item g_item_7\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item g_mosiac_item grid_mosiac_item\" style=\"padding-bottom:200%;\"><div class=\"g_mosiac_item_inner\"><a href=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/rom-1-hj-rnerom-mot-gaten-2-etg-500-k_orig.jpeg\" data-rel=\"lightbox\" class=\"gallery-link\"><div class=\"g_mosiac_item_image_case kt-intrinsic\"><div itemprop=\"image\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"800\" src=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/rom-1-hj-rnerom-mot-gaten-2-etg-500-k_orig-400x800.jpeg\"    class=\"kt-gallery-img\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/rom-1-hj-rnerom-mot-gaten-2-etg-500-k_orig-400x800.jpeg\"><meta itemprop=\"width\" content=\"400px\"><meta itemprop=\"height\" content=\"800px\"><\/div><\/div><\/a><\/div><\/div><\/div><div class=\"col-xxl-25 col-xl-6 col-md-6 col-sm-8 col-xs-8 col-ss-8 mosaic-sm-wide-grid-size g_item g_item_8\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item g_mosiac_item grid_mosiac_item\" style=\"padding-bottom:100%;\"><div class=\"g_mosiac_item_inner\"><a href=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/french-town-houses-scaled.jpeg\" data-rel=\"lightbox\" class=\"gallery-link\"><div class=\"g_mosiac_item_image_case kt-intrinsic\"><div itemprop=\"image\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/french-town-houses-scaled-800x800.jpeg\" srcset=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/french-town-houses-scaled-800x800.jpeg 800w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/french-town-houses-300x300.jpeg 300w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/french-town-houses-1024x1024.jpeg 1024w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/french-town-houses-150x150.jpeg 150w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/french-town-houses-768x768.jpeg 768w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/french-town-houses-1536x1536.jpeg 1536w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/french-town-houses-2048x2048.jpeg 2048w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/french-town-houses-500x500.jpeg 500w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/french-town-houses-100x100.jpeg 100w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/french-town-houses-scaled-1600x1600.jpeg 1600w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/french-town-houses-scaled-400x400.jpeg 400w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\"  class=\"kt-gallery-img\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/french-town-houses-scaled-800x800.jpeg\"><meta itemprop=\"width\" content=\"800px\"><meta itemprop=\"height\" content=\"800px\"><\/div><\/div><\/a><\/div><\/div><\/div><div class=\"col-xxl-25 col-xl-3 col-md-3 col-sm-4 col-xs-4 col-ss-4 mosaic-grid-size g_item g_item_9\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item g_mosiac_item grid_mosiac_item\" style=\"padding-bottom:100%;\"><div class=\"g_mosiac_item_inner\"><a href=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/MQ-Wedding44-scaled.jpeg\" data-rel=\"lightbox\" class=\"gallery-link\"><div class=\"g_mosiac_item_image_case kt-intrinsic\"><div itemprop=\"image\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/MQ-Wedding44-scaled-400x400.jpeg\" srcset=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/MQ-Wedding44-scaled-400x400.jpeg 400w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/MQ-Wedding44-150x150.jpeg 150w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/MQ-Wedding44-100x100.jpeg 100w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/MQ-Wedding44-scaled-800x800.jpeg 800w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\"  class=\"kt-gallery-img\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/MQ-Wedding44-scaled-400x400.jpeg\"><meta itemprop=\"width\" content=\"400px\"><meta itemprop=\"height\" content=\"400px\"><\/div><\/div><\/a><\/div><\/div><\/div><div class=\"col-xxl-25 col-xl-3 col-md-3 col-sm-4 col-xs-4 col-ss-4 mosaic-grid-size g_item g_item_10\"><div class=\"grid_item kt_item_fade_in kad_gallery_fade_in gallery_item g_mosiac_item grid_mosiac_item\" style=\"padding-bottom:100%;\"><div class=\"g_mosiac_item_inner\"><a href=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/St-Chinian-Platanes-Verts-scaled.jpg\" data-rel=\"lightbox\" class=\"gallery-link\"><div class=\"g_mosiac_item_image_case kt-intrinsic\"><div itemprop=\"image\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/St-Chinian-Platanes-Verts-scaled-400x400.jpg\" srcset=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/St-Chinian-Platanes-Verts-scaled-400x400.jpg 400w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/St-Chinian-Platanes-Verts-150x150.jpg 150w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/St-Chinian-Platanes-Verts-100x100.jpg 100w, https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/St-Chinian-Platanes-Verts-scaled-800x800.jpg 800w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\"  class=\"kt-gallery-img\" itemprop=\"contentUrl\" alt=\"\"><meta itemprop=\"url\" content=\"https:\/\/annettemorris.art\/wp-content\/uploads\/2022\/11\/St-Chinian-Platanes-Verts-scaled-400x400.jpg\"><meta itemprop=\"width\" content=\"400px\"><meta itemprop=\"height\" content=\"400px\"><\/div><\/div><\/a><\/div><\/div><\/div><\/div><\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A very special fully guided tour and 10 fabulous days of sketching and watercolour workshops exploring the magnificent Languedoc region of Southern France.  See more details and reserve via <a href=\"https:\/\/frenchfusion.com.au\/tours\/france-travel-sketching-with-annette-morris-june-2023\" target=\"_blank\" rel=\"noopener\">https:\/\/frenchfusion.com.au\/tours\/france-travel-sketching-with-annette-morris-june-2023<\/a>&hellip; <a class=\"kt-excerpt-readmore more-link\" href=\"https:\/\/annettemorris.art\/fr\/event\/travel-sketching-tour-hosted-by-french-fusion-travel\/\" aria-label=\"South of France Travel Sketching Tour\">Read More<\/a><\/p>\n","protected":false},"author":3,"featured_media":18368,"comment_status":"open","ping_status":"closed","template":"","meta":{"kt_blocks_editor_width":"","_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"Tribe__Tickets_Plus__Commerce__WooCommerce__Main","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":"","_links_to":"","_links_to_target":""},"tags":[],"tribe_events_cat":[199,203,172,59,543],"class_list":["post-18333","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-france","tribe_events_cat-languedoc","tribe_events_cat-sketch-holidays","tribe_events_cat-sketch-languedoc","tribe_events_cat-sketching-france","cat_france","cat_languedoc","cat_sketch-holidays","cat_sketch-languedoc","cat_sketching-france"],"aioseo_notices":[],"ticketed":false,"_links":{"self":[{"href":"https:\/\/annettemorris.art\/fr\/wp-json\/wp\/v2\/tribe_events\/18333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/annettemorris.art\/fr\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/annettemorris.art\/fr\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/annettemorris.art\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/annettemorris.art\/fr\/wp-json\/wp\/v2\/comments?post=18333"}],"version-history":[{"count":3,"href":"https:\/\/annettemorris.art\/fr\/wp-json\/wp\/v2\/tribe_events\/18333\/revisions"}],"predecessor-version":[{"id":20638,"href":"https:\/\/annettemorris.art\/fr\/wp-json\/wp\/v2\/tribe_events\/18333\/revisions\/20638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/annettemorris.art\/fr\/wp-json\/wp\/v2\/media\/18368"}],"wp:attachment":[{"href":"https:\/\/annettemorris.art\/fr\/wp-json\/wp\/v2\/media?parent=18333"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/annettemorris.art\/fr\/wp-json\/wp\/v2\/tags?post=18333"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/annettemorris.art\/fr\/wp-json\/wp\/v2\/tribe_events_cat?post=18333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}